{"id":260,"count":1,"description":"","link":"https:\/\/daveiga.es\/eu\/tag\/xornal-de-lemos","name":"xornal de lemos","slug":"xornal-de-lemos","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>xornal de lemos archivos - DAVEIGA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daveiga.es\/eu\/tag\/xornal-de-lemos\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"xornal de lemos archivos - DAVEIGA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daveiga.es\/eu\/tag\/xornal-de-lemos\" \/>\n<meta property=\"og:site_name\" content=\"DAVEIGA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daveiga.es\/wp-content\/uploads\/2025\/01\/Sitio-Web-con-Servicios-Restaurante-Naranja-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1927\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/daveiga.es\\\/tag\\\/xornal-de-lemos\",\"url\":\"https:\\\/\\\/daveiga.es\\\/tag\\\/xornal-de-lemos\",\"name\":\"xornal de lemos archivos - DAVEIGA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daveiga.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daveiga.es\\\/tag\\\/xornal-de-lemos#breadcrumb\"},\"inLanguage\":\"eu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daveiga.es\\\/tag\\\/xornal-de-lemos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/daveiga.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"xornal de lemos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daveiga.es\\\/#website\",\"url\":\"https:\\\/\\\/daveiga.es\\\/\",\"name\":\"DAVEIGA\",\"description\":\"Daveiga Producci\u00f3n Responsable- Mari\u00f1eiras\",\"publisher\":{\"@id\":\"https:\\\/\\\/daveiga.es\\\/#organization\"},\"alternateName\":\"Galletas Mari\u00f1eiras\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daveiga.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daveiga.es\\\/#organization\",\"name\":\"DAVEIGA\",\"alternateName\":\"Daveiga Producci\u00f3n Responsable\",\"url\":\"https:\\\/\\\/daveiga.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/daveiga.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daveiga.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/daveiga_blanco-02.png\",\"contentUrl\":\"https:\\\/\\\/daveiga.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/daveiga_blanco-02.png\",\"width\":601,\"height\":329,\"caption\":\"DAVEIGA\"},\"image\":{\"@id\":\"https:\\\/\\\/daveiga.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GalletasDaveiga\\\/\",\"https:\\\/\\\/www.instagram.com\\\/galletasmarineras\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@galletasmarineras\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"xornal de lemos archivos - DAVEIGA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daveiga.es\/eu\/tag\/xornal-de-lemos","og_locale":"en_US","og_type":"article","og_title":"xornal de lemos archivos - DAVEIGA","og_url":"https:\/\/daveiga.es\/eu\/tag\/xornal-de-lemos","og_site_name":"DAVEIGA","og_image":[{"width":1927,"height":768,"url":"https:\/\/daveiga.es\/wp-content\/uploads\/2025\/01\/Sitio-Web-con-Servicios-Restaurante-Naranja-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/daveiga.es\/tag\/xornal-de-lemos","url":"https:\/\/daveiga.es\/tag\/xornal-de-lemos","name":"xornal de lemos archivos - DAVEIGA","isPartOf":{"@id":"https:\/\/daveiga.es\/#website"},"breadcrumb":{"@id":"https:\/\/daveiga.es\/tag\/xornal-de-lemos#breadcrumb"},"inLanguage":"eu"},{"@type":"BreadcrumbList","@id":"https:\/\/daveiga.es\/tag\/xornal-de-lemos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/daveiga.es\/"},{"@type":"ListItem","position":2,"name":"xornal de lemos"}]},{"@type":"WebSite","@id":"https:\/\/daveiga.es\/#website","url":"https:\/\/daveiga.es\/","name":"DAVEIGA","description":"Daveiga Ekoizpen Erantzukizuna \u2013 Mari\u00f1eiras","publisher":{"@id":"https:\/\/daveiga.es\/#organization"},"alternateName":"Galletas Mari\u00f1eiras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daveiga.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/daveiga.es\/#organization","name":"DAVEIGA","alternateName":"Daveiga Producci\u00f3n Responsable","url":"https:\/\/daveiga.es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/daveiga.es\/#\/schema\/logo\/image\/","url":"https:\/\/daveiga.es\/wp-content\/uploads\/2024\/11\/daveiga_blanco-02.png","contentUrl":"https:\/\/daveiga.es\/wp-content\/uploads\/2024\/11\/daveiga_blanco-02.png","width":601,"height":329,"caption":"DAVEIGA"},"image":{"@id":"https:\/\/daveiga.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GalletasDaveiga\/","https:\/\/www.instagram.com\/galletasmarineras\/","https:\/\/www.tiktok.com\/@galletasmarineras"]}]}},"_links":{"self":[{"href":"https:\/\/daveiga.es\/eu\/wp-json\/wp\/v2\/tags\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daveiga.es\/eu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/daveiga.es\/eu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/daveiga.es\/eu\/wp-json\/wp\/v2\/posts?tags=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}